{"id":1237,"date":"2016-11-07T04:06:54","date_gmt":"2016-11-07T04:06:54","guid":{"rendered":"http:\/\/www.farmazoo.com\/Wordpress\/?page_id=12"},"modified":"2019-07-17T14:25:17","modified_gmt":"2019-07-17T14:25:17","slug":"contact","status":"publish","type":"page","link":"http:\/\/www.farmazoo.com\/Wordpress\/contact\/","title":{"rendered":"Contacto"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box hundred-percent-fullwidth non-hundred-percent-height-scrolling\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-bottom:0px;margin-top: 0px;'><div class=\"fusion-builder-row fusion-row \"><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-equal-height-columns\"  style='background-color: rgba(255,255,255,0);background-position: center center;background-repeat: no-repeat;padding-right:0px;padding-bottom:60px;padding-left:0px;margin-bottom: 2%;margin-top: 5%;'><div class=\"fusion-builder-row fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_2 fusion-builder-column-1 fusion-one-half fusion-column-first 1_2\"  style='margin-top:0px;margin-bottom:40px;width:50%;width:calc(50% - ( ( 8% ) * 0.5 ) );margin-right: 8%;'>\n\t\t\t\t\t<div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\">\n\t\t\t\t\t\t<div class=\"fusion-text\"><h3>Contactar<\/h3>\n<\/div><div class=\"fusion-text\"><p>Puede contactar con nosotros mediante el siguiente formulario de contacto.<\/p>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep sep-none\" style=\"margin-left: auto;margin-right: auto;margin-top:30px;\"><\/div><div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f207-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/Wordpress\/wp-json\/wp\/v2\/pages\/1237#wpcf7-f207-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"207\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.5.1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f207-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label><span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" \/><\/span> <\/label><\/p>\n<p><label><span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"correo electr\u00f3nico\" \/><\/span> <\/label><\/p>\n<p><label><span class=\"wpcf7-form-control-wrap Telefono\"><input type=\"tel\" name=\"Telefono\" value=\"Tel\u00e9fono\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label><span class=\"wpcf7-form-control-wrap tipo\"><select name=\"tipo\" class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\"><option value=\"Cliente\">Cliente<\/option><option value=\"Proveedor\">Proveedor<\/option><option value=\"Informaci\u00f3n\">Informaci\u00f3n<\/option><option value=\"Otros\">Otros<\/option><\/select><\/span><\/label><\/p>\n<p><label><span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\u00bfEn qu\u00e9 podemos ayudarle?\"><\/textarea><\/span> <\/label><\/p>\n<p><input type=\"submit\" value=\"Enviar solicitud\" class=\"wpcf7-form-control has-spinner wpcf7-submit\" \/><\/p>\n<p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"59\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"fusion-alert alert custom alert-custom fusion-alert-center wpcf7-response-output fusion-alert-capitalize alert-dismissable\" style=\"border-width:1px;\"><button style=\"color:;border-color:;\" type=\"button\" class=\"close toggle-alert\" data-dismiss=\"alert\" aria-hidden=\"true\">&times;<\/button><div class=\"fusion-alert-content-wrapper\"><span class=\"fusion-alert-content\"><\/span><\/div><\/div><\/form><\/div><div class=\"fusion-clearfix\"><\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_2 fusion-builder-column-2 fusion-one-half fusion-column-last 1_2\"  style='margin-top:0px;margin-bottom:40px;width:50%;width:calc(50% - ( ( 8% ) * 0.5 ) );'>\n\t\t\t\t\t<div class=\"fusion-column-wrapper\" style=\"padding: 0px 0px 0px 0px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"   data-bg-url=\"\">\n\t\t\t\t\t\t<div class=\"fusion-text\"><h3>Informaci\u00f3n de contacto<\/h3>\n<\/div><div class=\"fusion-sep-clear\"><\/div><div class=\"fusion-separator fusion-full-width-sep sep-none\" style=\"margin-left: auto;margin-right: auto;margin-top:5px;\"><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_5  fusion-one-fifth fusion-column-first fusion-no-small-visibility 1_5\"  style='margin-top: 0px;margin-bottom: 0px;width:20%;width:calc(20% - ( ( 0 ) * 0.2 ) );margin-right:0px;'><div class=\"fusion-column-wrapper\" style=\"background-color:#3ec492;padding: 20px 20px 30px 20px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"  data-bg-url=\"\"><div class=\"fusion-fa-align-center\"><i class=\"fontawesome-icon fa fa-volume-control-phone circle-yes\" style=\"border-color:rgba(61,67,76,0);background-color:rgba(61,67,76,0);font-size:39.6px;line-height:79.2px;height:79.2px;width:79.2px;color:#ffffff;\"><\/i><\/div><\/div><\/div><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_4_5  fusion-four-fifth fusion-column-last 4_5\"  style='margin-top: 0px;margin-bottom: 0px;width:80%;width:calc(80% - ( ( 0 ) * 0.8 ) );'><div class=\"fusion-column-wrapper\" style=\"background-color:#3ec492;padding: 25px 20px 40px 20px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"  data-bg-url=\"\"><div class=\"fusion-text\"><p style=\"color: #fff; margin-bottom: 0;\">Tel\u00e9fono<\/p>\n<\/div><div class=\"fusion-text\"><p style=\"font-size: 37px; line-height: 41px; margin-bottom: 0;\"><a style=\"color: #fff;\" href=\"tel:\/\/34922513780\">+34 922 513 780<\/a><\/p>\n<\/div><\/div><\/div><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_5  fusion-one-fifth fusion-column-first fusion-no-small-visibility 1_5\"  style='margin-top: 0px;margin-bottom: 0px;width:20%;width:calc(20% - ( ( 0 ) * 0.2 ) );margin-right:0px;'><div class=\"fusion-column-wrapper\" style=\"background-color:#3d434c;padding: 20px 20px 30px 20px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"  data-bg-url=\"\"><div class=\"fusion-fa-align-center\"><i class=\"fontawesome-icon fa fa-envelope-o circle-yes\" style=\"border-color:rgba(61,67,76,0);background-color:rgba(61,67,76,0);font-size:39.6px;line-height:79.2px;height:79.2px;width:79.2px;color:#3ec492;\"><\/i><\/div><\/div><\/div><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_4_5  fusion-four-fifth fusion-column-last 4_5\"  style='margin-top: 0px;margin-bottom: 0px;width:80%;width:calc(80% - ( ( 0 ) * 0.8 ) );'><div class=\"fusion-column-wrapper\" style=\"background-color:#3d434c;padding: 25px 20px 40px 20px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"  data-bg-url=\"\"><div class=\"fusion-text\"><p style=\"color: #fff; margin-bottom: 0;\">Correo electr\u00f3nico<\/p>\n<\/div><div class=\"fusion-text\"><p style=\"font-size: 30px; line-height: 41px; margin-bottom: 0;\"><a style=\"color: #fff;\" href=\"mailto:administraciony@farmazoo.es\">administracion@farmazoo.es<\/a><\/p>\n<\/div><\/div><\/div><\/div><div class=\"fusion-builder-row fusion-builder-row-inner fusion-row \"><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_1_5  fusion-one-fifth fusion-column-first fusion-no-small-visibility 1_5\"  style='margin-top: 0px;margin-bottom: 0px;width:20%;width:calc(20% - ( ( 0 ) * 0.2 ) );margin-right:0px;'><div class=\"fusion-column-wrapper\" style=\"background-color:#3d434c;padding: 20px 20px 30px 20px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"  data-bg-url=\"\"><div class=\"fusion-fa-align-center\"><i class=\"fontawesome-icon fa fa-map-marker circle-yes\" style=\"border-color:rgba(61,67,76,0);background-color:rgba(61,67,76,0);font-size:39.6px;line-height:79.2px;height:79.2px;width:79.2px;color:#3ec492;\"><\/i><\/div><\/div><\/div><div  class=\"fusion-layout-column fusion_builder_column fusion_builder_column_4_5  fusion-four-fifth fusion-column-last 4_5\"  style='margin-top: 0px;margin-bottom: 0px;width:80%;width:calc(80% - ( ( 0 ) * 0.8 ) );'><div class=\"fusion-column-wrapper\" style=\"background-color:#3d434c;padding: 25px 20px 40px 20px;background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\"  data-bg-url=\"\"><div class=\"fusion-text\"><p style=\"color: #fff; margin-bottom: 0;\">Encuentranos<\/p>\n<\/div><div class=\"fusion-text\"><p style=\"font-size: 37px; line-height: 41px; margin-bottom: 0;\"><a style=\"color: #fff;\" href=\"https:\/\/www.google.es\/maps\/place\/Farmazoo+Animal+Health+S.L.\/@28.330164,-16.3704567,17z\/data=!4m12!1m6!3m5!1s0xc402e84ab05ec9f:0xa749fd1d76473372!2sFarmazoo+Animal+Health+S.L.!8m2!3d28.330164!4d-16.368268!3m4!1s0xc402e84ab05ec9f:0xa749fd1d76473372!8m2!3d28.330164!4d-16.368268\">Google Maps<\/a><\/p>\n<\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contacto - Farmazoo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.farmazoo.com\/Wordpress\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contacto - Farmazoo\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.farmazoo.com\/Wordpress\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"Farmazoo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Farmazoo-Animal-Health-233668346662667\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-17T14:25:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Farmazoo2\" \/>\n<meta name=\"twitter:site\" content=\"@Farmazoo2\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\">\n\t<meta name=\"twitter:data1\" content=\"admin\">\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data2\" content=\"5 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.farmazoo.com\/Wordpress\/#organization\",\"name\":\"Farmazoo Animal Health\",\"url\":\"http:\/\/www.farmazoo.com\/Wordpress\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/Farmazoo-Animal-Health-233668346662667\/\",\"https:\/\/www.instagram.com\/farmazooah\/\",\"https:\/\/www.linkedin.com\/company\/farmazoo-animal-health\/\",\"https:\/\/www.youtube.com\/channel\/UCi2CvwPPbkn5pxZ_dIUOJKQ\",\"https:\/\/twitter.com\/Farmazoo2\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/www.farmazoo.com\/Wordpress\/#logo\",\"inLanguage\":\"es\",\"url\":\"http:\/\/www.farmazoo.com\/Wordpress\/wp-content\/uploads\/2019\/04\/FARMAZOO-logo.jpg\",\"width\":\"190\",\"height\":\"159\",\"caption\":\"Farmazoo Animal Health\"},\"image\":{\"@id\":\"http:\/\/www.farmazoo.com\/Wordpress\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.farmazoo.com\/Wordpress\/#website\",\"url\":\"http:\/\/www.farmazoo.com\/Wordpress\/\",\"name\":\"Farmazoo\",\"description\":\"Animal Health\",\"publisher\":{\"@id\":\"http:\/\/www.farmazoo.com\/Wordpress\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.farmazoo.com\/Wordpress\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.farmazoo.com\/Wordpress\/contact\/#webpage\",\"url\":\"http:\/\/www.farmazoo.com\/Wordpress\/contact\/\",\"name\":\"Contacto - Farmazoo\",\"isPartOf\":{\"@id\":\"http:\/\/www.farmazoo.com\/Wordpress\/#website\"},\"datePublished\":\"2016-11-07T04:06:54+00:00\",\"dateModified\":\"2019-07-17T14:25:17+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.farmazoo.com\/Wordpress\/contact\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/pages\/1237"}],"collection":[{"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/comments?post=1237"}],"version-history":[{"count":9,"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/pages\/1237\/revisions"}],"predecessor-version":[{"id":1290,"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/pages\/1237\/revisions\/1290"}],"wp:attachment":[{"href":"http:\/\/www.farmazoo.com\/Wordpress\/wp-json\/wp\/v2\/media?parent=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}